{"id":2251,"date":"2025-06-10T06:46:03","date_gmt":"2025-06-10T06:46:03","guid":{"rendered":"https:\/\/milestonebanden.nl\/mz01z\/"},"modified":"2025-08-04T13:27:26","modified_gmt":"2025-08-04T13:27:26","slug":"mz01z","status":"publish","type":"page","link":"https:\/\/milestonebanden.nl\/pt-pt\/pneus-verao\/mz01z\/","title":{"rendered":"Milestone MZ01Z"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; make_equal=&#8221;on&#8221; specialty=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;-58deg&#8221; background_color_gradient_stops=&#8221;#f4f4f4 62%|rgba(255,255,255,0) 62%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/milestone-mz01z-nl.jpg&#8221; background_position=&#8221;center_left&#8221; inner_max_width=&#8221;1280px&#8221; custom_padding=&#8221;||0px||false|false&#8221; background_last_edited=&#8221;on|phone&#8221; use_background_color_gradient_phone=&#8221;on&#8221; background_color_gradient_stops_phone=&#8221;#f4f4f4 100%|rgba(255,255,255,0) 100%&#8221; custom_css_free_form=&#8221;@media (max-width: 767px) {||selector .et_pb_row {||display: flex!important;||flex-direction: column-reverse;||}||selector .et_pb_row .et_pb_image_0 {||position: relative!important;||}||selector .et_pb_column.et_pb_column_1_2.et_pb_column_0 {||margin-bottom: 0!important;||}||}&#8221; box_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/07\/milestone-mz01z-nl.png&#8221; alt=&#8221;Milestone MZ01Z&#8221; title_text=&#8221;Milestone MZ01Z&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; positioning=&#8221;absolute&#8221; position_origin_a=&#8221;bottom_center&#8221; width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; specialty_columns=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||12%||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;2em&#8221; ul_font_size=&#8221;16px&#8221; ul_line_height=&#8221;2em&#8221; header_font=&#8221;Ubuntu|700|||||||&#8221; header_text_color=&#8221;#009c60&#8243; header_font_size=&#8221;36px&#8221; custom_css_free_form=&#8221;selector li {||    padding-top: 1em;||}||||selector ::marker {||    font-family: FontAwesome;||    content: %22%92f00c%22;||    color: #009c60;||    font-size: 16px;||    padding-right: 40px !important;||}||selector li {||    padding-left: 10px;||    text-indent: 0px;||}&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Milestone MZ01Z<\/h1>\n<p>Pneu de ver\u00e3o para carros m\u00e9dios e de luxo. Combina ader\u00eancia, conforto e efici\u00eancia para uma condu\u00e7\u00e3o segura e relaxada \u2013 mesmo com chuva de ver\u00e3o.<\/p>\n<ul>\n<li>Piso avan\u00e7ado garante estabilidade e confian\u00e7a ao volante.<\/li>\n<li>Sistema inteligente de drenagem para maior controlo em piso molhado.<\/li>\n<li>Design que reduz o consumo e as emiss\u00f5es \u2013 bom para a carteira e para o ambiente.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;4%||4%||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;margin: auto 0 0;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Ubuntu|700|||||||&#8221; text_font_size=&#8221;32px&#8221; global_colors_info=&#8221;{}&#8221;]Gama de medidas[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dipi_advanced_tabs use_tabs_fullwidth=&#8221;off&#8221; use_tabs_fullwidth_phone=&#8221;off&#8221; tabs_container_padding=&#8221;0px|0px|10px|0px|false|true&#8221; tabs_container_margin=&#8221;10px|0px|10px|0px|false|true&#8221; tabs_item_padding=&#8221;10px|10px|10px|20px|false|false&#8221; tabs_active_item_padding=&#8221;10px|10px|10px|20px|false|false&#8221; content_padding=&#8221;0px|0px|0px|0px|true|false&#8221; content_margin=&#8221;0px|10px|0px|0px|true|false&#8221; tabs_item_active_bg_color=&#8221;#009c60&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;Ubuntu|700|||||||&#8221; title_font_size=&#8221;20px&#8221; title_active_text_color=&#8221;#FFFFFF&#8221; subtitle_font=&#8221;Ubuntu|700|||||||&#8221; subtitle_font_size=&#8221;18px&#8221; subtitle_active_text_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][dipi_advanced_tabs_item title=&#8221;30&#8243; subtitle=&#8221;Series&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<table id=\"tablepress-39\" class=\"tablepress tablepress-id-39\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">SIZE<\/th><th class=\"column-2\">XL<\/th><th class=\"column-3\">LI<\/th><th class=\"column-4\">SI<\/th><th class=\"column-5\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-fuel.png\" \/><\/th><th class=\"column-6\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-grip.png\" \/><\/th><th class=\"column-7\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-noise.png\" \/><\/th><th class=\"column-8\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/07\/ico-3pmsf.png\" \/><\/th><th class=\"column-9\">EPREL<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">245 30 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">90<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">275 30 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">97<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-39 from cache -->[\/dipi_advanced_tabs_item][dipi_advanced_tabs_item title=&#8221;35&#8243; subtitle=&#8221;Series&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<table id=\"tablepress-40\" class=\"tablepress tablepress-id-40\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">SIZE<\/th><th class=\"column-2\">XL<\/th><th class=\"column-3\">LI<\/th><th class=\"column-4\">SI<\/th><th class=\"column-5\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-fuel.png\" \/><\/th><th class=\"column-6\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-grip.png\" \/><\/th><th class=\"column-7\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-noise.png\" \/><\/th><th class=\"column-8\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/07\/ico-3pmsf.png\" \/><\/th><th class=\"column-9\">EPREL<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">215 35 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">84<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">255 35 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">94<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">215 35 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">85<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">225 35 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">88<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">235 35 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">91<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">245 35 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">93<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">255 35 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">96<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">255 35 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">102<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">315 35 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">110<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">245 35 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">245 35 R21<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">96<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">285 35 R22<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">106<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-40 from cache -->[\/dipi_advanced_tabs_item][dipi_advanced_tabs_item title=&#8221;40&#8243; subtitle=&#8221;Series&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<table id=\"tablepress-41\" class=\"tablepress tablepress-id-41\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">SIZE<\/th><th class=\"column-2\">XL<\/th><th class=\"column-3\">LI<\/th><th class=\"column-4\">SI<\/th><th class=\"column-5\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-fuel.png\" \/><\/th><th class=\"column-6\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-grip.png\" \/><\/th><th class=\"column-7\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-noise.png\" \/><\/th><th class=\"column-8\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/07\/ico-3pmsf.png\" \/><\/th><th class=\"column-9\">EPREL<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">205 40 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">84<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">215 40 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">87<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">215 40 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">89<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">225 40 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">92<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">235 40 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">245 40 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">97<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">255 40 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">99<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">255 40 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">225 40 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">93<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">245 40 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">98<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">275 40 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">106<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">245 40 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">99<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">255 40 R21<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">102<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-41 from cache -->[\/dipi_advanced_tabs_item][dipi_advanced_tabs_item title=&#8221;45&#8243; subtitle=&#8221;Series&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<table id=\"tablepress-42\" class=\"tablepress tablepress-id-42\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">SIZE<\/th><th class=\"column-2\">XL<\/th><th class=\"column-3\">LI<\/th><th class=\"column-4\">SI<\/th><th class=\"column-5\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-fuel.png\" \/><\/th><th class=\"column-6\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-grip.png\" \/><\/th><th class=\"column-7\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-noise.png\" \/><\/th><th class=\"column-8\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/07\/ico-3pmsf.png\" \/><\/th><th class=\"column-9\">EPREL<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">195 45 R16<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">84<\/td><td class=\"column-4\">V<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">71B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340106\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">205 45 R16<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">87<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">215 45 R16<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">90<\/td><td class=\"column-4\">V<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">205 45 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">88<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">215 45 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">91<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">225 45 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">94<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">245 45 R17<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">235 45 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">97<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">245 45 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">215 45 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">93<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">225 45 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">235 45 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">98<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">245 45 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">102<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">225 45 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">96<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">245 45 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">103<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-42 from cache -->[\/dipi_advanced_tabs_item][dipi_advanced_tabs_item title=&#8221;50&#8243; subtitle=&#8221;Series&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<table id=\"tablepress-43\" class=\"tablepress tablepress-id-43\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">SIZE<\/th><th class=\"column-2\">XL<\/th><th class=\"column-3\">LI<\/th><th class=\"column-4\">SI<\/th><th class=\"column-5\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-fuel.png\" \/><\/th><th class=\"column-6\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-grip.png\" \/><\/th><th class=\"column-7\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-noise.png\" \/><\/th><th class=\"column-8\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/07\/ico-3pmsf.png\" \/><\/th><th class=\"column-9\">EPREL<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">205 50 R16<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">87<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">71B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340108\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">195 50 R16<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">88<\/td><td class=\"column-4\">V<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">71B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340107\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">205 50 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">93<\/td><td class=\"column-4\">Y<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">72B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340113\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">215 50 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">72B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340110\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">225 50 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">98<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">245 50 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">104<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">72B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340119\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">215 50 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">92<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">225 50 R18<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">71B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340114\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">255 50 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">107<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">B<\/td><td class=\"column-7\">73B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340120\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-43 from cache -->[\/dipi_advanced_tabs_item][dipi_advanced_tabs_item title=&#8221;55&#8243; subtitle=&#8221;Series&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<table id=\"tablepress-44\" class=\"tablepress tablepress-id-44\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">SIZE<\/th><th class=\"column-2\">XL<\/th><th class=\"column-3\">LI<\/th><th class=\"column-4\">SI<\/th><th class=\"column-5\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-fuel.png\" \/><\/th><th class=\"column-6\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-grip.png\" \/><\/th><th class=\"column-7\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/06\/ico-noise.png\" \/><\/th><th class=\"column-8\"><img decoding=\"async\" src=\"https:\/\/milestonebanden.nl\/wp-content\/uploads\/2025\/07\/ico-3pmsf.png\" \/><\/th><th class=\"column-9\">EPREL<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">225 55 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">102<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">72B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340116\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">235 55 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">103<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">72B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340117\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">205 55 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">72B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340109\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">215 55 R17<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">98<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">72B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340112\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">235 55 R18<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">71B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340118\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">225 55 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">102<\/td><td class=\"column-4\">V<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">255 55 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">109<\/td><td class=\"column-4\">V<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">B<\/td><td class=\"column-7\">73B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340121\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">225 55 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">98<\/td><td class=\"column-4\">W<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">215 55 R18<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">99<\/td><td class=\"column-4\">V<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">72B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340111\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">205 55 R19<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">103<\/td><td class=\"column-4\">V<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">225 55 R19<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">99<\/td><td class=\"column-4\">V<\/td><td class=\"column-5\">C<\/td><td class=\"column-6\">C<\/td><td class=\"column-7\">71B<\/td><td class=\"column-8\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/td><td class=\"column-9\"><a href=\"https:\/\/eprel.ec.europa.eu\/screen\/product\/tyres\/2340115\" target=\"_blank\" rel=\"noopener\">Database<\/a><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">195 55 R20<\/td><td class=\"column-2\">XL<\/td><td class=\"column-3\">95<\/td><td class=\"column-4\">H<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-44 from cache -->[\/dipi_advanced_tabs_item][\/dipi_advanced_tabs][\/et_pb_column][\/et_pb_row][et_pb_row make_equal=&#8221;on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;margin: auto 0 0;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/milestonebanden.nl\/brochures\/Milestone-brochure-PT.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Transferir brochura&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#009c60&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;4px&#8221; button_font=&#8221;Ubuntu||||||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;8px||8px||true|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#007649&#8243; button_bg_enable_color__hover=&#8221;on&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Milestone MZ01Z Pneu de ver\u00e3o para carros m\u00e9dios e de luxo. Combina ader\u00eancia, conforto e efici\u00eancia para uma condu\u00e7\u00e3o segura e relaxada \u2013 mesmo com chuva de ver\u00e3o. Piso avan\u00e7ado garante estabilidade e confian\u00e7a ao volante. Sistema inteligente de drenagem para maior controlo em piso molhado. Design que reduz o consumo e as emiss\u00f5es \u2013 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4362,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"dipi_cpt_category":[],"class_list":["post-2251","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Milestone MZ01Z | Pneus Milestone<\/title>\n<meta name=\"description\" content=\"O Milestone MZ01Z \u00e9 um pneu de ver\u00e3o para carros de gama m\u00e9dia e de luxo. Combina ader\u00eancia e conforto para uma condu\u00e7\u00e3o segura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Milestone MZ01Z | Pneus Milestone\" \/>\n<meta property=\"og:description\" content=\"O Milestone MZ01Z \u00e9 um pneu de ver\u00e3o para carros de gama m\u00e9dia e de luxo. Combina ader\u00eancia e conforto para uma condu\u00e7\u00e3o segura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/\" \/>\n<meta property=\"og:site_name\" content=\"Milestone banden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T13:27:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/milestonebanden.nl\\\/pt-pt\\\/mz01z\\\/\",\"url\":\"https:\\\/\\\/milestonebanden.nl\\\/pt-pt\\\/mz01z\\\/\",\"name\":\"Milestone MZ01Z | Pneus Milestone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/milestonebanden.nl\\\/#website\"},\"datePublished\":\"2025-06-10T06:46:03+00:00\",\"dateModified\":\"2025-08-04T13:27:26+00:00\",\"description\":\"O Milestone MZ01Z \u00e9 um pneu de ver\u00e3o para carros de gama m\u00e9dia e de luxo. Combina ader\u00eancia e conforto para uma condu\u00e7\u00e3o segura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/milestonebanden.nl\\\/pt-pt\\\/mz01z\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/milestonebanden.nl\\\/pt-pt\\\/mz01z\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/milestonebanden.nl\\\/pt-pt\\\/mz01z\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/milestonebanden.nl\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milestone MZ01Z\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/milestonebanden.nl\\\/#website\",\"url\":\"https:\\\/\\\/milestonebanden.nl\\\/\",\"name\":\"Milestone banden\",\"description\":\"More than just a journey!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/milestonebanden.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Milestone MZ01Z | Pneus Milestone","description":"O Milestone MZ01Z \u00e9 um pneu de ver\u00e3o para carros de gama m\u00e9dia e de luxo. Combina ader\u00eancia e conforto para uma condu\u00e7\u00e3o segura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/","og_locale":"pt_PT","og_type":"article","og_title":"Milestone MZ01Z | Pneus Milestone","og_description":"O Milestone MZ01Z \u00e9 um pneu de ver\u00e3o para carros de gama m\u00e9dia e de luxo. Combina ader\u00eancia e conforto para uma condu\u00e7\u00e3o segura.","og_url":"https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/","og_site_name":"Milestone banden","article_modified_time":"2025-08-04T13:27:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/","url":"https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/","name":"Milestone MZ01Z | Pneus Milestone","isPartOf":{"@id":"https:\/\/milestonebanden.nl\/#website"},"datePublished":"2025-06-10T06:46:03+00:00","dateModified":"2025-08-04T13:27:26+00:00","description":"O Milestone MZ01Z \u00e9 um pneu de ver\u00e3o para carros de gama m\u00e9dia e de luxo. Combina ader\u00eancia e conforto para uma condu\u00e7\u00e3o segura.","breadcrumb":{"@id":"https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/milestonebanden.nl\/pt-pt\/mz01z\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/milestonebanden.nl\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Milestone MZ01Z"}]},{"@type":"WebSite","@id":"https:\/\/milestonebanden.nl\/#website","url":"https:\/\/milestonebanden.nl\/","name":"Milestone banden","description":"More than just a journey!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/milestonebanden.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/pages\/2251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/comments?post=2251"}],"version-history":[{"count":4,"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/pages\/2251\/revisions"}],"predecessor-version":[{"id":2291,"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/pages\/2251\/revisions\/2291"}],"up":[{"embeddable":true,"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/pages\/4362"}],"wp:attachment":[{"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/media?parent=2251"}],"wp:term":[{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/milestonebanden.nl\/pt-pt\/wp-json\/wp\/v2\/dipi_cpt_category?post=2251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}